{"id":43,"date":"2026-02-19T18:37:55","date_gmt":"2026-02-19T10:37:55","guid":{"rendered":"https:\/\/emeraldhoianriverside.ms2.decms.asia\/?page_id=43"},"modified":"2026-07-08T11:39:34","modified_gmt":"2026-07-08T03:39:34","slug":"premium-pool-garden-view","status":"publish","type":"page","link":"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/","title":{"rendered":"Premium Pool\/ Garden View"},"content":{"rendered":"<p>Premium Pool\/ Garden View (50m2) &#8211; \u0111\u1eafm m\u00ecnh trong s\u1ef1 th\u1ea3nh th\u01a1i v\u00e0 y\u00ean b\u00ecnh trong t\u00e2m h\u1ed3n. Kh\u00f4ng gian r\u1ed9ng r\u00e3i \u0111\u01b0\u1ee3c b\u00e0i tr\u00ed \u1ea5m c\u00fang v\u00e0 th\u00e2n m\u1eadt mang trong m\u00ecnh \u0111\u01b0\u1eddng n\u00e9t ki\u1ebfn tr\u00fac v\u0103n h\u00f3a H\u1ed9i An \u0111\u01b0\u1ee3c l\u1ea5y c\u1ea3m h\u1ee9ng t\u1eeb khu v\u01b0\u1eddn r\u1ef1c r\u1ee1 b\u1ea5t t\u1eadn b\u00ean ngo\u00e0i ban c\u00f4ng l\u1edbn. T\u1ea7m nh\u00ecn cao r\u00e1o t\u1ea1i khu v\u01b0\u1eddn nhi\u1ec7t \u0111\u1edbi xanh m\u01b0\u1edbt.<br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n<p class=\"bel-price\">\u24d8 \u0110\u00e2y l\u00e0 m\u1ed9t trong nh\u1eefng m\u1ee9c gi\u00e1 th\u1ea5p nh\u1ea5t \u0111\u01b0\u1ee3c t\u00ecm th\u1ea5y g\u1ea7n \u0111\u00e2y. Gi\u00e1 th\u1ef1c t\u1ebf c\u00f3 th\u1ec3 thay \u0111\u1ed5i t\u00f9y theo ng\u00e0y l\u01b0u tr\u00fa b\u1ea1n ch\u1ecdn v\u00e0 t\u00ecnh tr\u1ea1ng ph\u00f2ng c\u00f2n tr\u1ed1ng<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Premium Pool\/ Garden View (50m2) &#8211; \u0111\u1eafm m\u00ecnh trong s\u1ef1 th\u1ea3nh th\u01a1i v\u00e0 y\u00ean b\u00ecnh trong t\u00e2m h\u1ed3n. Kh\u00f4ng gian r\u1ed9ng r\u00e3i \u0111\u01b0\u1ee3c b\u00e0i tr\u00ed \u1ea5m c\u00fang v\u00e0 th\u00e2n m\u1eadt mang trong m\u00ecnh \u0111\u01b0\u1eddng n\u00e9t ki\u1ebfn tr\u00fac v\u0103n h\u00f3a H\u1ed9i An \u0111\u01b0\u1ee3c l\u1ea5y c\u1ea3m h\u1ee9ng t\u1eeb khu v\u01b0\u1eddn r\u1ef1c r\u1ee1 b\u1ea5t t\u1eadn b\u00ean ngo\u00e0i ban [&hellip;]<\/p>\n","protected":false},"author":90,"featured_media":0,"parent":60,"menu_order":3,"comment_status":"closed","ping_status":"closed","template":"template-single-room.php","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Premium Pool\/ Garden View - Emerald Hoi An Riverside Resort<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/\" \/>\n<meta property=\"og:locale\" content=\"vi_VN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premium Pool\/ Garden View - Emerald Hoi An Riverside Resort\" \/>\n<meta property=\"og:description\" content=\"Premium Pool\/ Garden View (50m2) &#8211; \u0111\u1eafm m\u00ecnh trong s\u1ef1 th\u1ea3nh th\u01a1i v\u00e0 y\u00ean b\u00ecnh trong t\u00e2m h\u1ed3n. Kh\u00f4ng gian r\u1ed9ng r\u00e3i \u0111\u01b0\u1ee3c b\u00e0i tr\u00ed \u1ea5m c\u00fang v\u00e0 th\u00e2n m\u1eadt mang trong m\u00ecnh \u0111\u01b0\u1eddng n\u00e9t ki\u1ebfn tr\u00fac v\u0103n h\u00f3a H\u1ed9i An \u0111\u01b0\u1ee3c l\u1ea5y c\u1ea3m h\u1ee9ng t\u1eeb khu v\u01b0\u1eddn r\u1ef1c r\u1ee1 b\u1ea5t t\u1eadn b\u00ean ngo\u00e0i ban [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/\" \/>\n<meta property=\"og:site_name\" content=\"Emerald Hoi An Riverside Resort\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T03:39:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/\",\"url\":\"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/\",\"name\":\"Premium Pool\/ Garden View - Emerald Hoi An Riverside Resort\",\"isPartOf\":{\"@id\":\"https:\/\/emeraldhoianriverside.com\/vi\/#website\"},\"datePublished\":\"2026-02-19T10:37:55+00:00\",\"dateModified\":\"2026-07-08T03:39:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/#breadcrumb\"},\"inLanguage\":\"vi-VN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/emeraldhoianriverside.com\/vi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ph\u00f2ng\",\"item\":\"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Premium Pool\/ Garden View\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/emeraldhoianriverside.com\/vi\/#website\",\"url\":\"https:\/\/emeraldhoianriverside.com\/vi\/\",\"name\":\"Emerald Hoi An Riverside Resort\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/emeraldhoianriverside.com\/vi\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"vi-VN\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premium Pool\/ Garden View - Emerald Hoi An Riverside Resort","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/","og_locale":"vi_VN","og_type":"article","og_title":"Premium Pool\/ Garden View - Emerald Hoi An Riverside Resort","og_description":"Premium Pool\/ Garden View (50m2) &#8211; \u0111\u1eafm m\u00ecnh trong s\u1ef1 th\u1ea3nh th\u01a1i v\u00e0 y\u00ean b\u00ecnh trong t\u00e2m h\u1ed3n. Kh\u00f4ng gian r\u1ed9ng r\u00e3i \u0111\u01b0\u1ee3c b\u00e0i tr\u00ed \u1ea5m c\u00fang v\u00e0 th\u00e2n m\u1eadt mang trong m\u00ecnh \u0111\u01b0\u1eddng n\u00e9t ki\u1ebfn tr\u00fac v\u0103n h\u00f3a H\u1ed9i An \u0111\u01b0\u1ee3c l\u1ea5y c\u1ea3m h\u1ee9ng t\u1eeb khu v\u01b0\u1eddn r\u1ef1c r\u1ee1 b\u1ea5t t\u1eadn b\u00ean ngo\u00e0i ban [&hellip;]","og_url":"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/","og_site_name":"Emerald Hoi An Riverside Resort","article_modified_time":"2026-07-08T03:39:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/","url":"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/","name":"Premium Pool\/ Garden View - Emerald Hoi An Riverside Resort","isPartOf":{"@id":"https:\/\/emeraldhoianriverside.com\/vi\/#website"},"datePublished":"2026-02-19T10:37:55+00:00","dateModified":"2026-07-08T03:39:34+00:00","breadcrumb":{"@id":"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/#breadcrumb"},"inLanguage":"vi-VN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/premium-pool-garden-view\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/emeraldhoianriverside.com\/vi\/"},{"@type":"ListItem","position":2,"name":"Ph\u00f2ng","item":"https:\/\/emeraldhoianriverside.com\/vi\/rooms-suite\/"},{"@type":"ListItem","position":3,"name":"Premium Pool\/ Garden View"}]},{"@type":"WebSite","@id":"https:\/\/emeraldhoianriverside.com\/vi\/#website","url":"https:\/\/emeraldhoianriverside.com\/vi\/","name":"Emerald Hoi An Riverside Resort","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emeraldhoianriverside.com\/vi\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"vi-VN"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/emeraldhoianriverside.com\/vi\/wp-json\/wp\/v2\/pages\/43"}],"collection":[{"href":"https:\/\/emeraldhoianriverside.com\/vi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/emeraldhoianriverside.com\/vi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/emeraldhoianriverside.com\/vi\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/emeraldhoianriverside.com\/vi\/wp-json\/wp\/v2\/comments?post=43"}],"version-history":[{"count":0,"href":"https:\/\/emeraldhoianriverside.com\/vi\/wp-json\/wp\/v2\/pages\/43\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/emeraldhoianriverside.com\/vi\/wp-json\/wp\/v2\/pages\/60"}],"wp:attachment":[{"href":"https:\/\/emeraldhoianriverside.com\/vi\/wp-json\/wp\/v2\/media?parent=43"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}